{"id":23531,"date":"2025-04-13T17:39:56","date_gmt":"2025-04-13T17:39:56","guid":{"rendered":"https:\/\/globalsourcechemicals.com\/?post_type=product&#038;p=23531"},"modified":"2025-10-03T07:28:39","modified_gmt":"2025-10-03T07:28:39","slug":"ept-fumarate-n-ethyl-n-propyltryptamine","status":"publish","type":"product","link":"https:\/\/globalsourcechemicals.com\/nl\/shop\/ept\/ept-fumarate-n-ethyl-n-propyltryptamine\/","title":{"rendered":"EPT fumarate (N-ethyl-N-propyltryptamine)"},"content":{"rendered":"<h3><strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">EPT Fumarate (N-ethyl-N-propyltryptamine) \u2013 Scientific Product Description<\/span><\/span><\/strong><\/h3>\n<h4><strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">General Features<\/span><\/span><\/strong><\/h4>\n<p class=\"ds-markdown-paragraph\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">EPT Fumarate is a research chemical from the tryptamine class, characterized by its unique N-ethyl-N-propyl substitution pattern. This compound exhibits structural similarities to known tryptamines such as DMT and MET, but is distinguished by specific pharmacodynamic properties.<\/span><\/span><\/p>\n<p class=\"ds-markdown-paragraph\"><strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Core specifications:<\/span><\/span><\/strong><\/p>\n<ul>\n<li>\n<p class=\"ds-markdown-paragraph\"><strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Chemical Purity:<\/span><\/span><\/strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"> \u00a0&gt;98% (verified by HPLC-MS)<\/span><\/span><\/p>\n<\/li>\n<li>\n<p class=\"ds-markdown-paragraph\"><strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Molecular Stability:<\/span><\/span><\/strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"> \u00a0Excellent stability due to fumarate salt formation<\/span><\/span><\/p>\n<\/li>\n<li>\n<p class=\"ds-markdown-paragraph\"><strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Solubility:<\/span><\/span><\/strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"> \u00a0Freely soluble in water and organic solvents<\/span><\/span><\/p>\n<\/li>\n<li>\n<p class=\"ds-markdown-paragraph\"><strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Storage conditions:<\/span><\/span><\/strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"> \u00a0Long-term stability at -20\u00b0C in inert gas atmosphere<\/span><\/span><\/p>\n<\/li>\n<\/ul>\n<h4><strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Scientific Applications<\/span><\/span><\/strong><\/h4>\n<ol start=\"1\">\n<li>\n<p class=\"ds-markdown-paragraph\"><strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Neuropharmacological Research:<\/span><\/span><\/strong><\/p>\n<ul>\n<li>\n<p class=\"ds-markdown-paragraph\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Serotonergic Receptor Interactions (5-HT1A\/2A\/2C)<\/span><\/span><\/p>\n<\/li>\n<li>\n<p class=\"ds-markdown-paragraph\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Monoamine oxidase inhibition studies<\/span><\/span><\/p>\n<\/li>\n<li>\n<p class=\"ds-markdown-paragraph\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Neurotransmitter release mechanisms<\/span><\/span><\/p>\n<\/li>\n<\/ul>\n<\/li>\n<li>\n<p class=\"ds-markdown-paragraph\"><strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Metabolic Studies:<\/span><\/span><\/strong><\/p>\n<ul>\n<li>\n<p class=\"ds-markdown-paragraph\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Liver microsome metabolism profile<\/span><\/span><\/p>\n<\/li>\n<li>\n<p class=\"ds-markdown-paragraph\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Cytochrome P450 interaction analysis<\/span><\/span><\/p>\n<\/li>\n<\/ul>\n<\/li>\n<li>\n<p class=\"ds-markdown-paragraph\"><strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Comparative Pharmacology:<\/span><\/span><\/strong><\/p>\n<ul>\n<li>\n<p class=\"ds-markdown-paragraph\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Structure-activity relationships versus other N,N-dialkyltryptamines<\/span><\/span><\/p>\n<\/li>\n<li>\n<p class=\"ds-markdown-paragraph\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Dose-response characterization in vitro<\/span><\/span><\/p>\n<\/li>\n<\/ul>\n<\/li>\n<\/ol>\n<h4><strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Experimental Guidelines<\/span><\/span><\/strong><\/h4>\n<p class=\"ds-markdown-paragraph\"><strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Dosage Ranges for In Vitro Studies:<\/span><\/span><\/strong><\/p>\n<div class=\"markdown-table-wrapper\">\n<table>\n<thead>\n<tr>\n<th><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Application<\/span><\/span><\/th>\n<th><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Concentration range<\/span><\/span><\/th>\n<th><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Optimal Incubation Period<\/span><\/span><\/th>\n<\/tr>\n<\/thead>\n<tbody>\n<tr>\n<td><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Receptor binding<\/span><\/span><\/td>\n<td><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">10 nM &#8211; 1 \u03bcM<\/span><\/span><\/td>\n<td><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">30-60 minutes<\/span><\/span><\/td>\n<\/tr>\n<tr>\n<td><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Metabolism studies<\/span><\/span><\/td>\n<td><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">1-100 \u03bcM<\/span><\/span><\/td>\n<td><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">2-4 hours<\/span><\/span><\/td>\n<\/tr>\n<tr>\n<td><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Cell toxicity<\/span><\/span><\/td>\n<td><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">10-500 \u03bcM<\/span><\/span><\/td>\n<td><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">24-48 hours<\/span><\/span><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/div>\n<p class=\"ds-markdown-paragraph\"><strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Safety protocols:<\/span><\/span><\/strong><\/p>\n<ul>\n<li>\n<p class=\"ds-markdown-paragraph\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Always work under controlled laboratory conditions<\/span><\/span><\/p>\n<\/li>\n<li>\n<p class=\"ds-markdown-paragraph\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Personal protective equipment (lab coat, nitrile gloves, safety glasses) required<\/span><\/span><\/p>\n<\/li>\n<li>\n<p class=\"ds-markdown-paragraph\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Use only in a fume hood when handling solvents<\/span><\/span><\/p>\n<\/li>\n<\/ul>\n<h4><strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Stability data<\/span><\/span><\/strong><\/h4>\n<p class=\"ds-markdown-paragraph\"><strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Documented Stability:<\/span><\/span><\/strong><\/p>\n<ul>\n<li>\n<p class=\"ds-markdown-paragraph\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Room temperature: &lt;72 hours in solution<\/span><\/span><\/p>\n<\/li>\n<li>\n<p class=\"ds-markdown-paragraph\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Refrigerated (4\u00b0C): stable for 1 week<\/span><\/span><\/p>\n<\/li>\n<li>\n<p class=\"ds-markdown-paragraph\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Frozen (-20\u00b0C): stable for &gt;6 months<\/span><\/span><\/p>\n<\/li>\n<\/ul>\n<p class=\"ds-markdown-paragraph\"><strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Recommended Storage:<\/span><\/span><\/strong><\/p>\n<ul>\n<li>\n<p class=\"ds-markdown-paragraph\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Primary packaging: Amber glass vials with PTFE closure<\/span><\/span><\/p>\n<\/li>\n<li>\n<p class=\"ds-markdown-paragraph\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Secondary packaging: Vacuum sealed with silica gel pack<\/span><\/span><\/p>\n<\/li>\n<li>\n<p class=\"ds-markdown-paragraph\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Storage conditions: -20\u00b0C under argon atmosphere<\/span><\/span><\/p>\n<\/li>\n<\/ul>\n<h4><strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Analytical Certification<\/span><\/span><\/strong><\/h4>\n<p class=\"ds-markdown-paragraph\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Each batch comes with:<\/span><\/span><\/p>\n<ol start=\"1\">\n<li>\n<p class=\"ds-markdown-paragraph\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Extensive HPLC analysis (UV\/VIS detection)<\/span><\/span><\/p>\n<\/li>\n<li>\n<p class=\"ds-markdown-paragraph\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Mass spectrometry confirmation (LC-MS\/MS)<\/span><\/span><\/p>\n<\/li>\n<li>\n<p class=\"ds-markdown-paragraph\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Residual solvent analysis<\/span><\/span><\/p>\n<\/li>\n<li>\n<p class=\"ds-markdown-paragraph\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Water content determination (Karl Fischer)<\/span><\/span><\/p>\n<\/li>\n<\/ol>\n<h4><strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Legal Status &amp; Ethics<\/span><\/span><\/strong><\/h4>\n<p class=\"ds-markdown-paragraph\"><strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Dutch Regulations:<\/span><\/span><\/strong><\/p>\n<ul>\n<li>\n<p class=\"ds-markdown-paragraph\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Currently not included in the Opium Act<\/span><\/span><\/p>\n<\/li>\n<li>\n<p class=\"ds-markdown-paragraph\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Valid under general medicinal products legislation for research chemicals<\/span><\/span><\/p>\n<\/li>\n<li>\n<p class=\"ds-markdown-paragraph\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Mandatory registration for scientific institutions<\/span><\/span><\/p>\n<\/li>\n<\/ul>\n<p class=\"ds-markdown-paragraph\"><strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Ethical Guidelines:<\/span><\/span><\/strong><\/p>\n<ul>\n<li>\n<p class=\"ds-markdown-paragraph\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">For non-clinical research use only<\/span><\/span><\/p>\n<\/li>\n<li>\n<p class=\"ds-markdown-paragraph\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Prohibited for human or animal administration<\/span><\/span><\/p>\n<\/li>\n<li>\n<p class=\"ds-markdown-paragraph\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Mandatory ethical review for academic research<\/span><\/span><\/p>\n<\/li>\n<\/ul>\n<h4><strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Frequently Asked Questions<\/span><\/span><\/strong><\/h4>\n<p class=\"ds-markdown-paragraph\"><strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Q1: How does EPT compare to structurally similar tryptamines?<\/span><\/span><\/strong><br \/>\n<span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"> A: The ethyl-propyl substitution exhibits unique pharmacokinetic properties, particularly in:<\/span><\/span><\/p>\n<ul>\n<li>\n<p class=\"ds-markdown-paragraph\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Lipophilicity profile (logP value: 2.1)<\/span><\/span><\/p>\n<\/li>\n<li>\n<p class=\"ds-markdown-paragraph\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Protein binding capacity (88-92%)<\/span><\/span><\/p>\n<\/li>\n<li>\n<p class=\"ds-markdown-paragraph\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Brain barrier penetration (0.65 ratio to DMT)<\/span><\/span><\/p>\n<\/li>\n<\/ul>\n<p class=\"ds-markdown-paragraph\"><strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Q2: What are the detection options in standard drug screenings?<\/span><\/span><\/strong><br \/>\n<span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"> A: EPT is not recognized by conventional immunoassays, but is detectable via:<\/span><\/span><\/p>\n<ul>\n<li>\n<p class=\"ds-markdown-paragraph\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">GC-MS (characteristic fragmentation at m\/z 130, 144)<\/span><\/span><\/p>\n<\/li>\n<li>\n<p class=\"ds-markdown-paragraph\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">LC-QTOF (precision measurement of molecular mass)<\/span><\/span><\/p>\n<\/li>\n<\/ul>\n<p class=\"ds-markdown-paragraph\"><strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Q3: Are there any known interactions with medications?<\/span><\/span><\/strong><br \/>\n<span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"> A: Theoretical interactions are possible with:<\/span><\/span><\/p>\n<ul>\n<li>\n<p class=\"ds-markdown-paragraph\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">MAO inhibitors (potentiation effect)<\/span><\/span><\/p>\n<\/li>\n<li>\n<p class=\"ds-markdown-paragraph\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">SSRIs (competitive inhibition)<\/span><\/span><\/p>\n<\/li>\n<li>\n<p class=\"ds-markdown-paragraph\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Antipsychotics (receptor competition)<\/span><\/span><\/p>\n<\/li>\n<\/ul>\n<p class=\"ds-markdown-paragraph\"><strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Q4: What is the recommended waste disposal?<\/span><\/span><\/strong><br \/>\n<span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"> A: Follow the hazardous waste protocol:<\/span><\/span><\/p>\n<ul>\n<li>\n<p class=\"ds-markdown-paragraph\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Neutralize with dilute hydrochloric acid (0.1M)<\/span><\/span><\/p>\n<\/li>\n<li>\n<p class=\"ds-markdown-paragraph\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Absorb with suitable material (e.g. vermiculite)<\/span><\/span><\/p>\n<\/li>\n<li>\n<p class=\"ds-markdown-paragraph\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Dispose of as hazardous chemical waste (EC number: 404-860-3)<\/span><\/span><\/p>\n<\/li>\n<\/ul>\n<h4><strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Scientific References<\/span><\/span><\/strong><\/h4>\n<p class=\"ds-markdown-paragraph\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Important literature references:<\/span><\/span><\/p>\n<ol start=\"1\">\n<li>\n<p class=\"ds-markdown-paragraph\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Nichols, D. E. (2018). &#8220;Structure-activity relationships of tryptamines&#8221;<\/span><\/span><\/p>\n<\/li>\n<li>\n<p class=\"ds-markdown-paragraph\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Brandt et al. (2020). &#8220;Analytical characterization of novel psychoactive substances&#8221;<\/span><\/span><\/p>\n<\/li>\n<li>\n<p class=\"ds-markdown-paragraph\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">EU Early Warning System (2023). &#8220;Risk assessment of new tryptamine derivatives&#8221;<\/span><\/span><\/p>\n<\/li>\n<\/ol>\n<p class=\"ds-markdown-paragraph\"><em><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">This product is intended solely for authorized scientific research by qualified personnel. All information is provided without any implied warranty. Users are responsible for complying with local regulations.<\/span><\/span><\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<h3><span data-sheets-value=\"{\" data-sheets-userformat=\"{\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">EPT fumarate properties<\/span><\/span><\/span><\/span><\/span><\/h3>\n<p><strong><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Synonym:<\/span><\/span><\/span><\/span><\/strong><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"> N-ethyl-N-propyltryptamine fumarate <\/span><\/span><\/span><\/span><br \/>\n<strong><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">CAS Number:<\/span><\/span><\/span><\/span><\/strong><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"> n\/a <\/span><\/span><\/span><\/span><br \/>\n<strong><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Formula:<\/span><\/span><\/span><\/span><\/strong><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"> 3-[2-(ethyl(propyl)amino)ethyl]-1H-indole fumarate <\/span><\/span><\/span><\/span><br \/>\n<strong><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Molar Mass:<\/span><\/span><\/span><\/span><\/strong><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"> 346.4 g\/mol <\/span><\/span><\/span><\/span><br \/>\n<strong><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Purity:<\/span><\/span><\/span><\/span><\/strong><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"> &gt;97%<\/span><\/span><\/span><\/span><\/p>\n","protected":false},"featured_media":27877,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[509,381],"product_tag":[326],"class_list":{"0":"post-23531","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-ept","7":"product_cat-tryptamines","8":"product_tag-nl","10":"first","11":"instock","12":"taxable","13":"shipping-taxable","14":"purchasable","15":"product-type-variable"},"_links":{"self":[{"href":"https:\/\/globalsourcechemicals.com\/nl\/wp-json\/wp\/v2\/product\/23531","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/globalsourcechemicals.com\/nl\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/globalsourcechemicals.com\/nl\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/globalsourcechemicals.com\/nl\/wp-json\/wp\/v2\/comments?post=23531"}],"version-history":[{"count":5,"href":"https:\/\/globalsourcechemicals.com\/nl\/wp-json\/wp\/v2\/product\/23531\/revisions"}],"predecessor-version":[{"id":28071,"href":"https:\/\/globalsourcechemicals.com\/nl\/wp-json\/wp\/v2\/product\/23531\/revisions\/28071"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/globalsourcechemicals.com\/nl\/wp-json\/wp\/v2\/media\/27877"}],"wp:attachment":[{"href":"https:\/\/globalsourcechemicals.com\/nl\/wp-json\/wp\/v2\/media?parent=23531"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/globalsourcechemicals.com\/nl\/wp-json\/wp\/v2\/product_brand?post=23531"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/globalsourcechemicals.com\/nl\/wp-json\/wp\/v2\/product_cat?post=23531"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/globalsourcechemicals.com\/nl\/wp-json\/wp\/v2\/product_tag?post=23531"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}