{"id":24814,"date":"2025-04-13T17:43:14","date_gmt":"2025-04-13T17:43:14","guid":{"rendered":"https:\/\/globalsourcechemicals.com\/?post_type=product&#038;p=24814"},"modified":"2025-10-02T16:40:35","modified_gmt":"2025-10-02T16:40:35","slug":"3d-mxe-40mg-pellet","status":"publish","type":"product","link":"https:\/\/globalsourcechemicals.com\/it\/negozio\/arilcicloesilammina\/3d-mxe-40mg-pellet\/","title":{"rendered":"Pellet 3D-MXE da 40 mg"},"content":{"rendered":"<h1 class=\"ds-markdown-paragraph\"><strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Pellet 3D-MXE da 40 mg: sostanza chimica innovativa per la ricerca scientifica<\/span><\/span><\/strong><\/h1>\n<p><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">3d mxe<\/span><\/span><\/p>\n<h3><strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Informazioni su 3D-MXE<\/span><\/span><\/strong><\/h3>\n<p class=\"ds-markdown-paragraph\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">3D-MXE \u00e8 una sostanza chimica di ricerca appartenente alla classe delle arilcicloesilammine dissociative, strutturalmente simile alla MXE (metossietamina). Questa sostanza \u00e8 destinata esclusivamente alla ricerca farmacologica e neuroscientifica avanzata in ambienti di laboratorio controllati.<\/span><\/span><\/p>\n<h3><strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Caratteristiche principali del prodotto<\/span><\/span><\/strong><\/h3>\n<p class=\"ds-markdown-paragraph\">\u2714\u00a0<strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Dosaggio di precisione<\/span><\/span><\/strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"> \u00a0\u2013 40 mg per pellet per risultati di ricerca riproducibili <\/span><\/span><br \/>\n\u2714\u00a0<strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Formulazione avanzata<\/span><\/span><\/strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"> \u00a0\u2013 Biodisponibilit\u00e0 ottimale per studi in vitro <\/span><\/span><br \/>\n\u2714\u00a0<strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Composizione stabile<\/span><\/span><\/strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"> \u00a0\u2013 Conservabilit\u00e0 a lungo termine in condizioni appropriate <\/span><\/span><br \/>\n\u2714\u00a0<strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Qualit\u00e0 certificata<\/span><\/span><\/strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"> \u00a0\u2013 Disponibile il rapporto del test HPLC (purezza &gt;97%)<\/span><\/span><\/p>\n<h3><strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Potenziali aree di ricerca<\/span><\/span><\/strong><\/h3>\n<p class=\"ds-markdown-paragraph\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">\u2022 Studi sull&#039;antagonismo del recettore NMDA <\/span><\/span><br \/>\n<span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">\u2022 Ricerca sui meccanismi neuroprotettivi <\/span><\/span><br \/>\n<span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">\u2022 Analisi del profilo dell&#039;effetto dissociativo <\/span><\/span><br \/>\n<span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">\u2022 Farmacodinamica comparativa con composti correlati<\/span><\/span><\/p>\n<h3><strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Manuale di laboratorio<\/span><\/span><\/strong><\/h3>\n<p class=\"ds-markdown-paragraph\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">\u25c9\u00a0 <\/span><\/span><strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Magazzinaggio<\/span><\/span><\/strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"> : Conservare a 2-8\u00b0C nella confezione originale a prova di luce <\/span><\/span><br \/>\n<span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">\u25c9\u00a0 <\/span><\/span><strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Sicurezza<\/span><\/span><\/strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"> : Utilizzare sempre in un ambiente di laboratorio controllato <\/span><\/span><br \/>\n<span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">\u25c9\u00a0 <\/span><\/span><strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Dosaggio<\/span><\/span><\/strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"> : Per ulteriori sottodosaggi \u00e8 necessaria un&#039;attrezzatura di pesatura analitica accurata<\/span><\/span><\/p>\n<h3><strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Informazioni sull&#039;ordine<\/span><\/span><\/strong><\/h3>\n<ul>\n<li>\n<p class=\"ds-markdown-paragraph\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Disponibile in confezioni da 10 pellet<\/span><\/span><\/p>\n<\/li>\n<li>\n<p class=\"ds-markdown-paragraph\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Incluso certificato analitico dettagliato<\/span><\/span><\/p>\n<\/li>\n<li>\n<p class=\"ds-markdown-paragraph\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Solo per istituti di ricerca qualificati<\/span><\/span><\/p>\n<\/li>\n<\/ul>\n<h3><strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Stato legale e sicurezza<\/span><\/span><\/strong><\/h3>\n<p class=\"ds-markdown-paragraph\">\u26a0\u00a0<strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Non destinato all&#039;uso umano<\/span><\/span><\/strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"> \u00a0\u2013 Solo per la ricerca in vitro. <\/span><\/span><br \/>\n\u26a0<span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Lo stato normativo varia a seconda del Paese: i ricercatori devono attenersi alle normative locali. <\/span><\/span><br \/>\n\u26a0<span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Richiede l&#039;approvazione istituzionale per l&#039;acquisto.<\/span><\/span><\/p>\n<p class=\"ds-markdown-paragraph\"><strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Misure di sicurezza critiche<\/span><\/span><\/strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"> : <\/span><\/span><br \/>\n<span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">\u2022 Lavorare sempre con dispositivi di protezione individuale (camice, guanti, occhiali di sicurezza) <\/span><\/span><br \/>\n<span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">\u2022 Eseguire la ricerca solo sotto cappa chimica <\/span><\/span><br \/>\n<span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">\u2022 Non lavorare mai in isolamento, ma sempre con un collega ricercatore presente<\/span><\/span><\/p>\n<h3><strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Supporto scientifico<\/span><\/span><\/strong><\/h3>\n<p class=\"ds-markdown-paragraph\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Il nostro dipartimento di ricerca offre: <\/span><\/span><br \/>\n<span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">\u2192 Assistenza tecnica nella progettazione sperimentale <\/span><\/span><br \/>\n<span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">\u2192 Consulenza sulla metodologia analitica <\/span><\/span><br \/>\n<span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">\u2192 Materiale di riferimento per il controllo di qualit\u00e0<\/span><\/span><\/p>\n<p class=\"ds-markdown-paragraph\"><strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Nota importante<\/span><\/span><\/strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"> : <\/span><\/span><br \/>\n<span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Le presenti informazioni hanno esclusivamente scopo didattico e sono fornite in un contesto strettamente scientifico. Tutte le ricerche devono essere condotte nel rispetto delle leggi e dei regolamenti applicabili.<\/span><\/span><\/p>\n<p class=\"ds-markdown-paragraph\"><em><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Questo prodotto non \u00e8 destinato all&#039;uso diagnostico, terapeutico o ricreativo. Un uso improprio pu\u00f2 comportare gravi rischi per la salute. <\/span><\/span><\/em><a href=\"https:\/\/globalsourcechemicals.com\/it\/negozio\/lisergamidi\/1v-lsd-150-mcg-blotters\/\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Blotter 1V-LSD 150 MCG <\/span><\/span><\/a><a href=\"https:\/\/globalsourcechemicals.com\/it\/negozio\/pellet-2\/o-pellet-dsmt-50mg\/\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Pellet di O-DSMT da 50 mg <\/span><\/span><\/a><a href=\"https:\/\/globalsourcechemicals.com\/it\/negozio\/lisergamidi\/1-cp-di-lsd-150-mcg\/\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">1cP-LSD 150 MCG Art Blotters <\/span><\/span><\/a><a href=\"https:\/\/globalsourcechemicals.com\/it\/negozio\/iboga-ibogaina\/acquistare-ibogaina-cloridrato-online\/\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Acquista Ibogaina HCL <\/span><\/span><\/a><a href=\"https:\/\/globalsourcechemicals.com\/it\/negozio\/iboga-ibogaina\/corteccia-di-radice-di-iboga\/\"><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Corteccia di radice di iboga<\/span><\/span><\/a><\/p>","protected":false},"excerpt":{"rendered":"<h3><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Propriet\u00e0 3D-MXE<\/span><\/span><\/h3>\n<p><strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Sinonimo:<\/span><\/span><\/strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"> Deossimetossetamina <\/span><\/span><br \/>\n<strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Numero CAS:<\/span><\/span><\/strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"> 681440-83-5 <\/span><\/span><br \/>\n<strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Formula:<\/span><\/span><\/strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"> 5-deidro-1,3-chinodimetano <\/span><\/span><br \/>\n<strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Massa molare:<\/span><\/span><\/strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"> 103,14 g\/mol <\/span><\/span><br \/>\n<strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\">Purezza:<\/span><\/span><\/strong><span dir=\"auto\" style=\"vertical-align: inherit;\"><span dir=\"auto\" style=\"vertical-align: inherit;\"> &gt;97%<\/span><\/span><\/p>","protected":false},"featured_media":27784,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[71,406,429,324],"product_tag":[316,326],"class_list":{"0":"post-24814","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-arylcyclohexylamine","7":"product_cat-dmxe","8":"product_cat-dmxe-pellets","9":"product_cat-pellets-for-pellet","10":"product_tag-3d-mxe","11":"product_tag-nl","13":"first","14":"instock","15":"taxable","16":"shipping-taxable","17":"purchasable","18":"product-type-variable"},"_links":{"self":[{"href":"https:\/\/globalsourcechemicals.com\/it\/wp-json\/wp\/v2\/product\/24814","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/globalsourcechemicals.com\/it\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/globalsourcechemicals.com\/it\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/globalsourcechemicals.com\/it\/wp-json\/wp\/v2\/comments?post=24814"}],"version-history":[{"count":5,"href":"https:\/\/globalsourcechemicals.com\/it\/wp-json\/wp\/v2\/product\/24814\/revisions"}],"predecessor-version":[{"id":27978,"href":"https:\/\/globalsourcechemicals.com\/it\/wp-json\/wp\/v2\/product\/24814\/revisions\/27978"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/globalsourcechemicals.com\/it\/wp-json\/wp\/v2\/media\/27784"}],"wp:attachment":[{"href":"https:\/\/globalsourcechemicals.com\/it\/wp-json\/wp\/v2\/media?parent=24814"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/globalsourcechemicals.com\/it\/wp-json\/wp\/v2\/product_brand?post=24814"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/globalsourcechemicals.com\/it\/wp-json\/wp\/v2\/product_cat?post=24814"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/globalsourcechemicals.com\/it\/wp-json\/wp\/v2\/product_tag?post=24814"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}